{"id":4149,"date":"2026-08-28T13:03:27","date_gmt":"2026-08-28T11:03:27","guid":{"rendered":"https:\/\/bigagency.sk\/?post_type=hero_slider_logos&#038;p=4149"},"modified":"2026-08-28T13:03:27","modified_gmt":"2026-08-28T11:03:27","slug":"panasonic","status":"publish","type":"hero_slider_logos","link":"https:\/\/bigagency.sk\/de\/hero_slider_logos\/panasonic\/","title":{"rendered":"Panasonic"},"featured_media":0,"template":"","class_list":["post-4149","hero_slider_logos","type-hero_slider_logos","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Panasonic - Big Agency<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bigagency.sk\/de\/hero_slider_logos\/panasonic\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Panasonic - Big Agency\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bigagency.sk\/de\/hero_slider_logos\/panasonic\/\" \/>\n<meta property=\"og:site_name\" content=\"Big Agency\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bigagency.sk\\\/hero_slider_logos\\\/panasonic\\\/\",\"url\":\"https:\\\/\\\/bigagency.sk\\\/hero_slider_logos\\\/panasonic\\\/\",\"name\":\"Panasonic - Big Agency\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bigagency.sk\\\/#website\"},\"datePublished\":\"2026-08-28T11:03:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bigagency.sk\\\/hero_slider_logos\\\/panasonic\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bigagency.sk\\\/hero_slider_logos\\\/panasonic\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bigagency.sk\\\/hero_slider_logos\\\/panasonic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Domovsk\u00e1 str\u00e1nka\",\"item\":\"https:\\\/\\\/bigagency.sk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Panasonic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bigagency.sk\\\/#website\",\"url\":\"https:\\\/\\\/bigagency.sk\\\/\",\"name\":\"Big Agency\",\"description\":\"Od firemn\u00fdch eventov a konferenci\u00ed po podporu predaja a pren\u00e1jom invent\u00e1ru a atrakci\u00ed. Agent\u00fara Big Agency v\u00e1m zabezpe\u010d\u00ed kompletn\u00e9 rie\u0161enia bez starost\u00ed \u2713\",\"publisher\":{\"@id\":\"https:\\\/\\\/bigagency.sk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bigagency.sk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bigagency.sk\\\/#organization\",\"name\":\"Big Agency\",\"url\":\"https:\\\/\\\/bigagency.sk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/bigagency.sk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bigagency.sk\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/bigagency.sk\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo.svg\",\"width\":142,\"height\":24,\"caption\":\"Big Agency\"},\"image\":{\"@id\":\"https:\\\/\\\/bigagency.sk\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Panasonic - Big Agency","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bigagency.sk\/de\/hero_slider_logos\/panasonic\/","og_locale":"de_DE","og_type":"article","og_title":"Panasonic - Big Agency","og_url":"https:\/\/bigagency.sk\/de\/hero_slider_logos\/panasonic\/","og_site_name":"Big Agency","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bigagency.sk\/hero_slider_logos\/panasonic\/","url":"https:\/\/bigagency.sk\/hero_slider_logos\/panasonic\/","name":"Panasonic - Big Agency","isPartOf":{"@id":"https:\/\/bigagency.sk\/#website"},"datePublished":"2026-08-28T11:03:27+00:00","breadcrumb":{"@id":"https:\/\/bigagency.sk\/hero_slider_logos\/panasonic\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bigagency.sk\/hero_slider_logos\/panasonic\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bigagency.sk\/hero_slider_logos\/panasonic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Domovsk\u00e1 str\u00e1nka","item":"https:\/\/bigagency.sk\/"},{"@type":"ListItem","position":2,"name":"Panasonic"}]},{"@type":"WebSite","@id":"https:\/\/bigagency.sk\/#website","url":"https:\/\/bigagency.sk\/","name":"Big Agency","description":"Od firemn\u00fdch eventov a konferenci\u00ed po podporu predaja a pren\u00e1jom invent\u00e1ru a atrakci\u00ed. Agent\u00fara Big Agency v\u00e1m zabezpe\u010d\u00ed kompletn\u00e9 rie\u0161enia bez starost\u00ed \u2713","publisher":{"@id":"https:\/\/bigagency.sk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bigagency.sk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/bigagency.sk\/#organization","name":"Big Agency","url":"https:\/\/bigagency.sk\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bigagency.sk\/#\/schema\/logo\/image\/","url":"https:\/\/bigagency.sk\/wp-content\/uploads\/2026\/03\/logo.svg","contentUrl":"https:\/\/bigagency.sk\/wp-content\/uploads\/2026\/03\/logo.svg","width":142,"height":24,"caption":"Big Agency"},"image":{"@id":"https:\/\/bigagency.sk\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/bigagency.sk\/de\/wp-json\/wp\/v2\/hero_slider_logos\/4149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bigagency.sk\/de\/wp-json\/wp\/v2\/hero_slider_logos"}],"about":[{"href":"https:\/\/bigagency.sk\/de\/wp-json\/wp\/v2\/types\/hero_slider_logos"}],"wp:attachment":[{"href":"https:\/\/bigagency.sk\/de\/wp-json\/wp\/v2\/media?parent=4149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}